{"id":12337,"date":"2017-12-01T16:08:33","date_gmt":"2017-12-01T16:08:33","guid":{"rendered":"http:\/\/www.radiolibertadmundo.com\/web\/?p=12337"},"modified":"2017-12-01T16:08:33","modified_gmt":"2017-12-01T16:08:33","slug":"alejandro-toledo-pide-citar-a-ppk-y-zavala-ante-la-fiscalia-por-interoceanica-sur","status":"publish","type":"post","link":"http:\/\/www.radiolibertadmundo.com\/web\/alejandro-toledo-pide-citar-a-ppk-y-zavala-ante-la-fiscalia-por-interoceanica-sur\/","title":{"rendered":"Alejandro Toledo pide citar a PPK y Zavala ante la Fiscal\u00eda por Interoce\u00e1nica Sur"},"content":{"rendered":"<p><a href=\"http:\/\/www.radiolibertadmundo.com\/web\/2017\/12\/01\/alejandro-toledo-pide-citar-a-ppk-y-zavala-ante-la-fiscalia-por-interoceanica-sur\/24129839_2018265188456306_567554118643949622_n\/\" rel=\"attachment wp-att-12338\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-12338\" src=\"http:\/\/www.radiolibertadmundo.com\/web\/wp-content\/uploads\/24129839_2018265188456306_567554118643949622_n.jpg\" alt=\"\" width=\"604\" height=\"340\" srcset=\"http:\/\/www.radiolibertadmundo.com\/web\/wp-content\/uploads\/24129839_2018265188456306_567554118643949622_n.jpg 604w, http:\/\/www.radiolibertadmundo.com\/web\/wp-content\/uploads\/24129839_2018265188456306_567554118643949622_n-300x169.jpg 300w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/><\/a><\/p>\n<p>Abogado del expresidente present\u00f3 la solicitud al despacho de Hamilton Castro por papel que cumplieron en la entrega de concesi\u00f3n<\/p>\n<p>Apunta y dispara. La defensa legal del exmandatario Alejandro Toledo, Roberto Su Rivadeneyra, present\u00f3 al Ministerio P\u00fablico una solicitud para ampliar las declaraciones del presidente de la Rep\u00fablica, Pedro Pablo Kuczynski Godard (PPK), a fin de que esclarezca su par<span class=\"text_exposed_show\">ticipaci\u00f3n en la adjudicaci\u00f3n de la Carretera Interoce\u00e1nica Sur y explique los supuestos v\u00ednculos que tendr\u00eda con la firma brasile\u00f1a Odebrecht, en referencia a una presunta consultor\u00eda y la ONG que form\u00f3 con el exrepresentante de la constructora en Per\u00fa, Jorge Barata, en noviembre del a\u00f1o 2007.<br \/>\nEl documento, entregado ayer al despacho del Equipo Especial de Investigaci\u00f3n del caso \u201cLava Jato\u201d -a cargo del fiscal Hamilton Castro- y al que tuvo acceso Correo, tambi\u00e9n expone la necesidad de recoger el testimonio del expresidente del Consejo de Ministros Fernando Zavala. Ello, debido a que, cuando ocup\u00f3 el cargo de viceministro de Econom\u00eda en el gobierno de Toledo, viaj\u00f3 en noviembre de 2004 junto al entonces mandatario a Brasil como parte de la Delegaci\u00f3n Oficial de Altos Funcionarios.<\/span><\/p>\n<div class=\"text_exposed_show\">\n<p>Asimismo, se contempla que se cite nuevamente al extitular del Ministerio de Transportes y Comunicaciones (MTC), Jos\u00e9 Ortiz Rivera, en cuyo periodo el Congreso promulg\u00f3 la Ley N\u00b0 28214, que aprob\u00f3 la exoneraci\u00f3n del Sistema Nacional de Inversi\u00f3n P\u00fablica (SNIP) al proyecto de la Interoce\u00e1nica Sur.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Abogado del expresidente present\u00f3 la solicitud al despacho de Hamilton Castro por papel que cumplieron en la entrega de concesi\u00f3n Apunta y dispara. La defensa <a class=\"mh-excerpt-more\" href=\"http:\/\/www.radiolibertadmundo.com\/web\/alejandro-toledo-pide-citar-a-ppk-y-zavala-ante-la-fiscalia-por-interoceanica-sur\/\" title=\"Alejandro Toledo pide citar a PPK y Zavala ante la Fiscal\u00eda por Interoce\u00e1nica Sur\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":12338,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5,3,16],"tags":[1240,1239,1238,470,65,1241],"class_list":["post-12337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","category-nacional","category-noticias","category-regional","tag-consejo-de-ministros","tag-hamilton-castro","tag-interoceanica","tag-ppk","tag-toledo","tag-zavala"],"_links":{"self":[{"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/posts\/12337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/comments?post=12337"}],"version-history":[{"count":2,"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/posts\/12337\/revisions"}],"predecessor-version":[{"id":12340,"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/posts\/12337\/revisions\/12340"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/media\/12338"}],"wp:attachment":[{"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/media?parent=12337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/categories?post=12337"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/tags?post=12337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}