{"id":11271,"date":"2017-11-02T16:07:57","date_gmt":"2017-11-02T16:07:57","guid":{"rendered":"http:\/\/www.radiolibertadmundo.com\/web\/?p=11271"},"modified":"2017-11-02T16:07:57","modified_gmt":"2017-11-02T16:07:57","slug":"alcalde-de-carabamba-sale-de-prision-tras-nueve-meses","status":"publish","type":"post","link":"http:\/\/www.radiolibertadmundo.com\/web\/alcalde-de-carabamba-sale-de-prision-tras-nueve-meses\/","title":{"rendered":"Alcalde de Carabamba sale de prisi\u00f3n tras nueve meses"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/laindustria.s3.amazonaws.com\/1509576496.jpg\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>La Libertad <\/strong><\/p>\n<p>El alcalde de Carabamba &#8211; Julcan, Segundo Ricardo Vega Cedano, abandon\u00f3 el penal el Milagro de Trujillo, luego de cumplir nueve meses de prisi\u00f3n preventiva, al ser investigado por la comisi\u00f3n del\u00a0<strong>delito de soborno o cohecho pasivo impropio en agravio del Estado<\/strong>, representado por la municipalidad distrital que representaba.<\/p>\n<p>Tal como se inform\u00f3 oportunamente, en el mes de febrero de 2016, el burgomaestre fue sorprendido por agentes de la Polic\u00eda Anticorrupci\u00f3n en un restaurante trujillano en circunstancias que recib\u00eda un presunto soborno de\u00a0<strong>5 mil soles de parte de ejecutivos de una empresa constructora<\/strong>\u00a0para favorecerlos en la adjudicaci\u00f3n de obras municipales.<\/p>\n<p>&nbsp;<\/p>\n<p>Los empresarios denunciaron el hecho ante la Fiscal\u00eda Anticorrupci\u00f3n, la misma que orden\u00f3 el operativo para la captura, de ah\u00ed que sorprendieron al burgomaestre con los billetes que previamente hab\u00edan sido fotocopiados.<\/p>\n<p><strong>La liberaci\u00f3n<\/strong><\/p>\n<p>El fiscal anticorrupci\u00f3n que investiga el caso, cuyo nombre no fue revelado en la resoluci\u00f3n, solicit\u00f3 el 28 de agosto la ampliaci\u00f3n de la prisi\u00f3n preventiva por cuatro meses m\u00e1s del alcalde Vega Cedano. El requerimiento fiscal fue declarado fundado por el Segundo Juzgado de Investigaci\u00f3n Preparatoria, dictamen que fue apelado por el abogado defensor C\u00e9sar Alva Flori\u00e1n.<\/p>\n<p>La Primera Sala de Apelaciones fue la encargada de deliberar sobre el caso, el \u00faltimo 23 del corriente. Durante la audiencia, a la que<strong>\u00a0no asisti\u00f3 el Fiscal Superior encargado de la carpeta fiscal<\/strong>\u00a0aduciendo estar delicado de salud, el abogado defensor del alcalde manifest\u00f3 a la sala que el escrito de ampliaci\u00f3n de prisi\u00f3n preventiva presentado por el Ministerio P\u00fablico no presenta documentos justificatorios, pero no s\u00f3lo eso, el Ministerio P\u00fablico al ser un \u00f3rgano corporativo debi\u00f3 haber tomado las medidas necesarias, trat\u00e1ndose de un reo en c\u00e1rcel.<\/p>\n<p>Ante esto, la Primera Sala de Apelaciones por unanimidad resuelve revocar el dictamen de requerimiento de ampliaci\u00f3n de prisi\u00f3n preventiva, reform\u00e1ndola y declar\u00e1ndola improcedente.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>&nbsp; La Libertad El alcalde de Carabamba &#8211; Julcan, Segundo Ricardo Vega Cedano, abandon\u00f3 el penal el Milagro de Trujillo, luego de cumplir nueve meses <a class=\"mh-excerpt-more\" href=\"http:\/\/www.radiolibertadmundo.com\/web\/alcalde-de-carabamba-sale-de-prision-tras-nueve-meses\/\" title=\"Alcalde de Carabamba sale de prisi\u00f3n tras nueve meses\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":11272,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,3,16],"tags":[59,692],"class_list":["post-11271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fotos","category-noticias","category-regional","tag-la-libertad","tag-seguridad-ciudadana"],"_links":{"self":[{"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/posts\/11271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/comments?post=11271"}],"version-history":[{"count":1,"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/posts\/11271\/revisions"}],"predecessor-version":[{"id":11273,"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/posts\/11271\/revisions\/11273"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/media\/11272"}],"wp:attachment":[{"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/media?parent=11271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/categories?post=11271"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiolibertadmundo.com\/web\/wp-json\/wp\/v2\/tags?post=11271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}